

{"id":40461,"date":"2021-06-05T16:00:58","date_gmt":"2021-06-05T19:00:58","guid":{"rendered":"http:\/\/portalfloresnoar.com\/floresnoar\/?p=40461"},"modified":"2021-11-24T10:50:01","modified_gmt":"2021-11-24T13:50:01","slug":"agenda-pe-workshop-cabeca-do-dragao-neste-mes-de-novembro-em-pernambuco","status":"publish","type":"post","link":"https:\/\/portalfloresnoar.com\/floresnoar\/agenda-pe-workshop-cabeca-do-dragao-neste-mes-de-novembro-em-pernambuco\/","title":{"rendered":"[AGENDA PE] Workshop Cabe\u00e7a do Drag\u00e3o\u00ae, neste m\u00eas de novembro, em Pernambuco"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-40463\" src=\"http:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2021\/11\/workshop-cabe\u00e7a-do-dragao-recife-700x700.jpeg\" alt=\"\" width=\"479\" height=\"479\" srcset=\"https:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2021\/11\/workshop-cabe\u00e7a-do-dragao-recife-700x700.jpeg 700w, https:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2021\/11\/workshop-cabe\u00e7a-do-dragao-recife-150x150.jpeg 150w, https:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2021\/11\/workshop-cabe\u00e7a-do-dragao-recife-300x300.jpeg 300w, https:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2021\/11\/workshop-cabe\u00e7a-do-dragao-recife-768x768.jpeg 768w, https:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2021\/11\/workshop-cabe\u00e7a-do-dragao-recife-100x100.jpeg 100w, https:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2021\/11\/workshop-cabe\u00e7a-do-dragao-recife.jpeg 800w\" sizes=\"(max-width: 479px) 100vw, 479px\" \/><br \/>\nA facilitadora Renata Villela realiza neste m\u00eas de novembro, no Recife e em Gravat\u00e1, o Workshop Cabe\u00e7a do Drag\u00e3o\u00ae, que une conhecimentos da Astrologia e das Novas Constela\u00e7\u00f5es Familiares. Al\u00e9m do workshop presencial em grupo, tamb\u00e9m \u00e9 oferecido o Workshop individual, que pode acontecer tanto presencialmente, como on-line.<\/p>\n<p>De acordo com Renata, o Workshop Cabe\u00e7a do Drag\u00e3o\u00ae \u00e9 um encontro de abordagem vivencial, \u00fanica, onde cada participante, atrav\u00e9s da Constela\u00e7\u00e3o de seu mapa natal, cria condi\u00e7\u00f5es de:<\/p>\n<p>OBSERVAR os padr\u00f5es familiares, pessoais e transpessoais que aparecem no seu mapa astrol\u00f3gico;<\/p>\n<p>VIVENCIAR sentimentos e sensa\u00e7\u00f5es, &#8216;falas&#8217; e movimentos de cada planeta e as rela\u00e7\u00f5es entre eles, percebendo a influ\u00eancia deles na vida;<\/p>\n<p>LIBERAR o que est\u00e1 impedindo a realiza\u00e7\u00e3o do prop\u00f3sito da alma.<\/p>\n<p>&#8220;A partir da\u00ed \u00e9 poss\u00edvel a realiza\u00e7\u00e3o de escolhas e a\u00e7\u00f5es rumo \u00e0 vida que voc\u00ea deseja construir. A viv\u00eancia proporciona o participante a dar um &#8216;passo qu\u00e2ntico&#8217; para o desenvolvimento pessoal e libera\u00e7\u00e3o da melhor vers\u00e3o de si&#8221;, informa a facilitadora.<\/p>\n<p>Criado por Patricia C. Vivas, por quem Renata foi formada, o Workshop e M\u00e9todo Cabe\u00e7a do Drag\u00e3o\u00ae combina os conhecimentos que Bert Hellinger trouxe com as constela\u00e7\u00f5es familiares juntamente com a Astrologia Evolutiva e Psicol\u00f3gica (Jung).<\/p>\n<p>&#8220;No mapa astrol\u00f3gico (mandala que os planetas, aspectos e signos desenham no c\u00e9u, no dia, hora e lugar em que nascemos) a Cabe\u00e7a do Drag\u00e3o, ou &#8216;Nodo Norte&#8217;, representa o que viemos fazer na Terra, nos convidando a olhar com respeito o que est\u00e1 acontecendo em nossa vida, se estamos na vida que viemos viver ou se alguma for\u00e7a pode estar confundindo a experi\u00eancia do nosso real prop\u00f3sito. Assim observamos onde e o que pode enfraquecer ou fortalecer a sua Cabe\u00e7a do Drag\u00e3o, ou seja, o seu prop\u00f3sito de alma&#8221;, explica Renata.<\/p>\n<p>PARA QUEM \u00c9 O WORKSHOP:<br \/>\nPara todos aqueles que est\u00e3o buscando dar mais um passo no desenvolvimento pessoal e autoconsci\u00eancia.<\/p>\n<p>COMO FUNCIONA:<br \/>\n1- O Workshop ser\u00e1 realizado presencialmente, em grupo, no Recife e em Gravata;<\/p>\n<p>2- O mapa astrol\u00f3gico de cada participante \u00e9 feito antecipadamente e &#8216;constelado&#8217; durante o encontro;<\/p>\n<p>3- No Workshop em grupo os participantes participam da Constela\u00e7\u00e3o dos mapas dos outros participantes do grupo, experienciando assim as energias dos astros, trabalhando todo o tempo em seu pr\u00f3prio benef\u00edcio e em ben\u00e9fico de todos.<\/p>\n<p>4- Na viv\u00eancia, cada participante \u00e9 convidado, atrav\u00e9s de exerc\u00edcios e medita\u00e7\u00e3o a se &#8216;sensibilizar&#8217; com suas percep\u00e7\u00f5es, se abrindo aos campos qu\u00e2nticos dos sistemas familiares, planet\u00e1rio e universal.<\/p>\n<p>5 &#8211; Estar\u00e1 sendo oferecido o Workshop individual presencial no Recife, e tamb\u00e9m on-line.<\/p>\n<p>IMPORTANTE: Em todos os eventos presenciais ser\u00e3o obedecidos todos os protocolos de seguran\u00e7a (uso de m\u00e1scaras, higieniza\u00e7\u00e3o das m\u00e3os, respeito ao distanciamento).<\/p>\n<p>FACILITADORA:<br \/>\n<strong>Renata Villela<\/strong> &#8211; Estudante e adepta da Astrologia, desde 1979. Em 2005 fez a forma\u00e7\u00e3o em Yoga Massagem Ayuvedica com Geetsh (Marcos Juc\u00e1) e desde ent\u00e3o vem trilhando este caminho onde corpo, alma e esp\u00edrito se encontram. Com mestrado em Natural Facelift Massage, \u00e9 Embaixadora da London Champissage International (escola de massagens indianas) no Brasil. Certificada como Facilitadora do M\u00e9todo \u201cWorkshop Cabe\u00e7a do Drag\u00e3o\u201d, pela pr\u00f3pria criadora na primeira turma de facilitadores, dentre outras forma\u00e7\u00f5es que a comp\u00f5em como profissional e ser humano. Neste momento continua seus estudos em Astrologia Evolutiva pela Escuela Astroterapeutica e Constela\u00e7\u00f5es Familiares no Insconfa &#8211; Madrid. \u00c9 monitora e supervisora na segunda turma de forma\u00e7\u00e3o do M\u00e9todo &#8220;Cabe\u00e7a do Drag\u00e3o\u00ae&#8221;.<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-40464\" src=\"http:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2021\/11\/workshop-cabe\u00e7a-do-dragao-no-recife.jpg\" alt=\"\" width=\"445\" height=\"445\" srcset=\"https:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2021\/11\/workshop-cabe\u00e7a-do-dragao-no-recife.jpg 610w, https:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2021\/11\/workshop-cabe\u00e7a-do-dragao-no-recife-150x150.jpg 150w, https:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2021\/11\/workshop-cabe\u00e7a-do-dragao-no-recife-300x300.jpg 300w, https:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2021\/11\/workshop-cabe\u00e7a-do-dragao-no-recife-100x100.jpg 100w\" sizes=\"(max-width: 445px) 100vw, 445px\" \/><\/p>\n<p><strong>WORKSHOP INDIVIDUAL NO RECIFE<\/strong><br \/>\n<strong>Dia:<\/strong> 19\/11\/2021 (sexta-feira)<br \/>\n<strong>Hora:<\/strong> atrav\u00e9s de agendamento<br \/>\n<strong>Investimento:<\/strong> R$ 593,00 (at\u00e9 10\/11)<br \/>\n<em>Obs.1: A partir desta data: R$ 639,00<\/em><\/p>\n<p><strong>WORKSHOP EM GRUPO NO RECIFE (at\u00e9 6 pessoas)<\/strong><br \/>\n<strong>Data:<\/strong> 20\/11\/2021 (s\u00e1bado)<br \/>\n<strong>Hora:<\/strong> das 8h30 \u00e0s 19h<br \/>\n<strong>Local:<\/strong> Espa\u00e7o Gerar Arteterapia e Bem-Estar &#8211; Rua Luiz Guimar\u00e3es, 253, Po\u00e7o da Panela, Recife-PE<\/p>\n<p><strong>Investimento:<\/strong> R$ 683,00 (at\u00e9 10\/11)<br \/>\n<em>Obs.1: A partir desta data: R$ 719,00<\/em><br \/>\n<em>Obs.2: Al\u00e9m do workshop esta inclu\u00eddo um coffee break<\/em><br \/>\n<em>Obs.3: Investimento para &#8216;Representante&#8217;: R$ 100,00 (a ser pago diretamente \u00e0 facilitadora).\u00a0Para ser Representante \u00e9 preciso j\u00e1 ter feito &#8216;a sua Cabe\u00e7a do Drag\u00e3o&#8217; com um facilitador credenciado pelo M\u00e9todo\u00ae.<\/em><\/p>\n<p><strong>Inscri\u00e7\u00f5es atrav\u00e9s deste link:<\/strong> <a href=\"https:\/\/www.sympla.com.br\/workshop-cabeca-do-dragaor-recife-gerar__1397110\" target=\"_blank\" rel=\"noopener\">https:\/\/www.sympla.com.br\/workshop-cabeca-do-dragaor-recife-gerar__1397110<\/a><\/p>\n<p><strong>MAIS INFORMA\u00c7\u00d5ES:<\/strong><br \/>\n<strong>Telefone\/WhatsApp:<\/strong>(48) 99948-5023 (Renata) | (81) 99760-6383 (Espa\u00e7o Gerar)<br \/>\n<strong>Instagram:<\/strong> <a href=\"https:\/\/www.instagram.com\/essencialsoul\/\" target=\"_blank\" rel=\"noopener\">@essencialsoul<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-40465\" src=\"http:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2021\/11\/workshop-cabe\u00e7a-do-dragao-gravata-pernambuco.jpg\" alt=\"\" width=\"445\" height=\"445\" srcset=\"https:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2021\/11\/workshop-cabe\u00e7a-do-dragao-gravata-pernambuco.jpg 610w, https:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2021\/11\/workshop-cabe\u00e7a-do-dragao-gravata-pernambuco-150x150.jpg 150w, https:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2021\/11\/workshop-cabe\u00e7a-do-dragao-gravata-pernambuco-300x300.jpg 300w, https:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2021\/11\/workshop-cabe\u00e7a-do-dragao-gravata-pernambuco-100x100.jpg 100w\" sizes=\"(max-width: 445px) 100vw, 445px\" \/><\/p>\n<p><strong>WORKSHOP EM GRUPO EM GRAVAT\u00c1 (at\u00e9 10 pessoas)<\/strong><br \/>\n<strong>Data:<\/strong> Dias 27 e 28 de novembro de 2021<br \/>\n<strong>Hora:<\/strong> Das 9h \u00e0s 19h<br \/>\n<strong>Local:<\/strong> Recanto Primavera, Rua Maria Olinda da Cruz 73, loteamento Baviera, Gravat\u00e1\/PE.<\/p>\n<p><strong>Investimento:<\/strong> R$ 740,00 (at\u00e9 15\/11)<br \/>\n<em>Obs.1: A partir desta data o valor ficar\u00e1 por: R$ 780,00<\/em><br \/>\n<em> Obs.2: No valor est\u00e3o inclu\u00eddas duas noites em quarto compartilhado e dois coffee break.<\/em><br \/>\n<em> Obs.3: Investimento para &#8220;Representante&#8221;: R$125,00 (pagamento diretamente com a facilitadora). Para ser Representante \u00e9 preciso j\u00e1 ter feito &#8216;a sua Cabe\u00e7a do Drag\u00e3o&#8217; com um facilitador credenciado pelo M\u00e9todo\u00ae.<\/em><\/p>\n<p><strong>Inscri\u00e7\u00f5es, atrav\u00e9s deste link:<\/strong> <a href=\"https:\/\/www.sympla.com.br\/workshop-cabeca-do-dragaor-gravata__1381771\" target=\"_blank\" rel=\"noopener\">https:\/\/www.sympla.com.br\/workshop-cabeca-do-dragaor-gravata__1381771<\/a><\/p>\n<p><strong>MAIS INFORMA\u00c7\u00d5ES<\/strong><br \/>\n<strong>Telefone\/WhatsApp:<\/strong> (48) 99948-5023 | (81) 9794 2898 (Silvia Gon\u00e7alves)<br \/>\n<strong>Instagram:<\/strong> <a href=\"https:\/\/www.instagram.com\/essencialsoul\/\" target=\"_blank\" rel=\"noopener\">@essencialsoul<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A facilitadora Renata Villela realiza neste m\u00eas de novembro, no Recife e em Gravat\u00e1, o Workshop Cabe\u00e7a do Drag\u00e3o\u00ae, que une conhecimentos da Astrologia e das Novas Constela\u00e7\u00f5es Familiares. Al\u00e9m do workshop presencial em grupo, tamb\u00e9m \u00e9 oferecido o Workshop individual, que pode acontecer tanto presencialmente, como on-line. De acordo com Renata, o Workshop Cabe\u00e7a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":40466,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[8,214],"tags":[18,531,295,515],"acf":[],"publishpress_future_action":{"enabled":false,"date":"1969-12-31 21:00:00","action":"","terms":[],"taxonomy":"","browser_timezone_offset":0},"_links":{"self":[{"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/posts\/40461"}],"collection":[{"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/comments?post=40461"}],"version-history":[{"count":0,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/posts\/40461\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/media\/40466"}],"wp:attachment":[{"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/media?parent=40461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/categories?post=40461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/tags?post=40461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}