

{"id":34811,"date":"2018-12-13T17:06:36","date_gmt":"2018-12-13T20:06:36","guid":{"rendered":"http:\/\/portalfloresnoar.com\/floresnoar\/?p=34811"},"modified":"2018-12-13T17:10:48","modified_gmt":"2018-12-13T20:10:48","slug":"integrando-saude-amar-a-deus-amando-a-si-mesmo-no-cultivo-de-uma-boa-alimentacao","status":"publish","type":"post","link":"https:\/\/portalfloresnoar.com\/floresnoar\/integrando-saude-amar-a-deus-amando-a-si-mesmo-no-cultivo-de-uma-boa-alimentacao\/","title":{"rendered":"[INTEGRANDO SA\u00daDE] Amar a Deus amando a si mesmo no cultivo de uma boa alimenta\u00e7\u00e3o"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter wp-image-34812\" src=\"http:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2018\/12\/receitas-culinarias-naturais.jpg\" alt=\"\" width=\"629\" height=\"400\" srcset=\"https:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2018\/12\/receitas-culinarias-naturais.jpg 640w, https:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2018\/12\/receitas-culinarias-naturais-300x191.jpg 300w\" sizes=\"(max-width: 629px) 100vw, 629px\" \/><\/p>\n<p>|\u00a0<em>Por Gabriela Sencades Migge*<\/em>\u00a0|<\/p>\n<p>No artigo anterior &#8216;<a href=\"http:\/\/portalfloresnoar.com\/floresnoar\/integrando-saude-amor-como-caminho-direto-amar-a-deus-amando-a-si-mesmo\/\" target=\"_blank\" rel=\"noopener\">Amar a Deus Amando a Si Mesmo<\/a>&#8216;, um \u00faltimo ponto foi uma sugest\u00e3o de pr\u00e1tica chamada de Metabhavana (medita\u00e7\u00e3o do amor universal), que consiste na repeti\u00e7\u00e3o e visualiza\u00e7\u00e3o do sentido das seguintes frases:<br \/>\n1. Que eu seja feliz (se visualize sendo e sentindo-se feliz e assim por diante);<br \/>\n2. Que eu supere todo o sofrimento;<br \/>\n3. Que eu encontre as verdadeiras causa da felicidade;<br \/>\n4. Que eu supere as verdadeiras causas do sofrimento;<br \/>\n5. Que eu supere todo o carma;<br \/>\n6. Que eu manifeste lucidez instant\u00e2nea e naturalmente;<br \/>\n7. Que eu desenvolva forma de beneficiar os seres verdadeiramente e<br \/>\n8. Que eu encontre nisso a fonte de alegria e felicidade.<\/p>\n<p>Isso \u00e9 um bom come\u00e7o. Mas, n\u00e3o pare por a\u00ed. Passo a passo, devagar, \u00e0 medida que ganhamos confian\u00e7a, vamos evoluir \u00e0 visualiza\u00e7\u00e3o e vamos para realiza\u00e7\u00e3o, passando ent\u00e3o a agir. Essa a\u00e7\u00e3o vem agora a partir da percep\u00e7\u00e3o de quais atitudes que tom\u00e1vamos que nos agredia profundamente. Come\u00e7amos ent\u00e3o a n\u00e3o nos agredir e a perceber que \u00e2mbito temos um \u201cn\u00f3\u201d mais complicado: fam\u00edlia, rela\u00e7\u00f5es amorosas, amizades, atividades f\u00edsicas, estudos, alimenta\u00e7\u00e3o, drogas, poder, dinheiro&#8230; enfim, rela\u00e7\u00f5es entre pessoas e com objetos que pode gerar depend\u00eancia ou indiferen\u00e7a em qualquer \u00e2mbito de nossa vida e nos tornam cegos, fazendo-nos agir contra n\u00f3s mesmos. Por\u00e9m, agora, vamos descortinando alguns v\u00e9us.<\/p>\n<p>A mudan\u00e7a sempre vem, n\u00e3o importa se lenta ou abrupta, ela acontece. E, quando vamos contemplando as situa\u00e7\u00f5es, vamos lidando com as situa\u00e7\u00f5es com maior naturalidade, mesmo que sejam super dif\u00edceis. Mas n\u00e3o precisamos estar iluminados para come\u00e7armos a agir \u00e9 necess\u00e1rio que a a\u00e7\u00e3o venha, pois a medida que vamos agindo vamos aprendendo tamb\u00e9m.<\/p>\n<p>Podemos come\u00e7ar com a\u00e7\u00f5es transformadoras mais simples e pequenas a fim de que possamos ir estabelecendo um continuum de mudan\u00e7as pequenas na perspectiva de que, em algum momento, elas transformar\u00e3o toda a nossa vida. Para melhor, assim espero!<\/p>\n<p>Que tal come\u00e7ar com algo simples, como a alimenta\u00e7\u00e3o, por exemplo. Preciso repetir que o que pode ser simples \u00e0s vezes n\u00e3o \u00e9 muito f\u00e1cil. E quando o assunto \u00e9 alimenta\u00e7\u00e3o \u00e9 necess\u00e1rio considerar que isso mexe diretamente com nossos apegos mais primitivos, nossas mem\u00f3rias mais afetivas, de amor e de cuidado que recebemos, mas que nem sempre nos levam a cultivar sa\u00fade, como o caso do \u201cleitinho quentinho\u201d que ganh\u00e1vamos daquele ente querido quando est\u00e1vamos gripados.\u00a0<span style=\"letter-spacing: 0em;\">Mas percebam, que, apesar de ser um gesto super amoroso, o leite talvez n\u00e3o seria o melhor dos alimentos para quem est\u00e1 com excesso de muco decorrente de processos inflamat\u00f3rios, pois o leite, quando de origem animal, vai contribuir para a prolifera\u00e7\u00e3o desse muco, piorando o processo inflamat\u00f3rio.<\/span><\/p>\n<p>Considerando isso como apenas um pequeno exemplo, ainda precisamos refletir a seguinte quest\u00e3o: ser\u00e1 que passamos a maior parte do tempo nos intoxicando ou nos nutrindo? Ser\u00e1 que a partir da escolha do que eu coloco para dentro do meu corpo eu posso estar cultivando alguma doen\u00e7a que com o passar de um tempo ela ir\u00e1 inevitavelmente se manifestar?<\/p>\n<p>E a sua mente? Como fica depois de ingerir a\u00e7\u00facares refinados, gorduras ruins em excesso, carnes com muitos horm\u00f4nios, rem\u00e9dios, doen\u00e7as e cheias de agrot\u00f3xicos tamb\u00e9m (lembre que um boi, por exemplo, acumula tanto agrot\u00f3xico quanto n\u00f3s seres humanos, pois essas subst\u00e2ncias s\u00e3o acumulativas em gorduras).<\/p>\n<p>Quando voc\u00ea come, qual a intens\u00e3o desse ato? Se nutrir? Sentir prazer apenas? Compensar car\u00eancias, ansiedades e medos pelo prazer da comida? A quem voc\u00ea est\u00e1 servindo na hora de se alimentar: seu ego ou seu corpo?<\/p>\n<p>Perceba que nosso corpo precisa do alimento certo para funcionar bem. Ao colocar coisas t\u00f3xicas para dentro de nosso corpo, este vai dar sinais sutis que n\u00e3o ligamos muito e, muitas vezes, nem associamos ao que comemos. \u00c9 o caso da digest\u00e3o lenta, sentimo-nos pesados, a mente fica confusa, let\u00e1rgica, gases, constipa\u00e7\u00e3o, sonol\u00eancia, mal cheiros e por a\u00ed vai. J\u00e1 ouviram aquela frase \u201ccomi tanto que fiquei triste.\u201d?<\/p>\n<p>Por\u00e9m, ao teimar e n\u00e3o dar ouvidos ao que o corpo est\u00e1 pedindo (repare que precisamos ouvir o que o corpo pede e n\u00e3o o ego), como, por exemplo, alimentos de f\u00e1cil digest\u00e3o, frescos, naturais, sem venenos, enfim, quando n\u00e3o ouvimos o pedido de nosso corpo, vamos cultivando doen\u00e7as de todos os tipos, por anos, at\u00e9 que elas despontam como um pedido de socorro de nosso corpo para n\u00f3s mesmos.<\/p>\n<p>Nesse sentido, toda doen\u00e7a \u00e9 um grito de socorro de nosso corpo que diz \u201cpor favor, pare de me tratar mal!\u201d, \u201cvoc\u00ea precisa mudar, sen\u00e3o vamos colapsar!\u201d. Importante considerar aqui que n\u00e3o \u00e9 s\u00f3 de alimentos que nosso corpo se nutre. Emo\u00e7\u00f5es t\u00f3xicas, como solid\u00e3o, tristeza, ci\u00fames, raiva, inveja, tristeza, tamb\u00e9m s\u00e3o p\u00e9ssimos \u201calimentos\u201d. Portanto, cuidado! Para uma boa nutri\u00e7\u00e3o \u00e9 preciso que ela seja integral tamb\u00e9m (em corpo, mente e esp\u00edrito).<\/p>\n<p>Mas bem&#8230; \u00e0 medida que vamos aprendendo a nos amar, n\u00f3s vamos ficando mais atentos ao pedidos de nosso corpo e assim vamos cuidando dele com carinho. Afinal, ele \u00e9 nosso ve\u00edculo, nossa casa neste mundo e, como toda casa, precisa de cuidados.<\/p>\n<p>E, nesse sentido, come\u00e7ar a dar o alimento adequado \u00e9 fazer uma grande reforma estrutural. Seria como transformar um corti\u00e7o em pal\u00e1cio, e dar a todos os seres que moram nele &#8211; no caso, c\u00e9lulas, bact\u00e9rias, \u00f3rg\u00e3os e tecidos &#8211; o t\u00edtulo de nobreza, ou melhor, talvez o de santidade, onde todos s\u00e3o igualmente importantes e reverenciados por n\u00f3s mesmos, o seu \u00fanico s\u00fadito, e que \u00e9 integralmente respons\u00e1vel por todo seu sustento e beleza (no caso, a sua sa\u00fade, pois corpo bonito \u00e9 corpo saud\u00e1vel, n\u00e3o importa a forma).<\/p>\n<p>Eu realmente n\u00e3o pretendo fazer apologias a este ou aquele estilo de se alimentar. N\u00e3o se trata disso. Quero aqui apenas abrir pontos de reflex\u00e3o sobre o assunto e deixar que o leitor procure o melhor e a partir da\u00ed aplique em sua vida.<\/p>\n<p>Com isso aspiro que suas escolhas sejam feitas com consci\u00eancia e liberdade. Sem influ\u00eancia de outras pessoas, da ind\u00fastria e\/ou do pr\u00f3prio aprisionamento do ego. Com muita observa\u00e7\u00e3o e experimenta\u00e7\u00e3o vamos intuindo naturalmente o que nosso corpo pede ou que nosso ego exige, vamos nos libertando das exig\u00eancias e nos orientando pelo bom senso. De forma natural, prazerosa tamb\u00e9m, mas que esse prazer esteja vinculado ao bom senso, unindo-o com a nutri\u00e7\u00e3o e a funcionalidade dos alimentos tamb\u00e9m, por que n\u00e3o n\u00e9!?.<\/p>\n<p>Minha aspira\u00e7\u00e3o \u00e9 que, sejam quais forem suas escolhas, que estas se baseiem na aspira\u00e7\u00e3o de que seu corpo seja seu templo sagrado a fim de manifestares a sua express\u00e3o divina, a sua melhor vers\u00e3o.<\/p>\n<p>Vamos come\u00e7ar?<\/p>\n<p>Deixo, ao final, algumas boas receitinhas, caso voc\u00ea n\u00e3o saiba por onde come\u00e7ar, mas deseja com sinceridade tentar.<\/p>\n<p><strong>Leites vegetais<\/strong> \u2013 podemos fazer com coco, frutas oleaginosas (castanhas, nozes, am\u00eandoas), amendoim, gergelim, enfim, existe uma grande variedade para todos os gostos e bolsos tamb\u00e9m. Os mais baratos s\u00e3o o de coco, de amendoim e de semente de girassol sem casca.<\/p>\n<p>S\u00e3o super vers\u00e1teis, podemos usar em tudo, substituindo o leite animal das receitas tradicionais. N\u00e3o altera em nada a textura, mas pode ser que deixe algum sabor, v\u00e1 testando os leites vegetais que mais se adequam ao seu paladar.<\/p>\n<p>O passo a passo b\u00e1sico \u00e9:<br \/>\n1. Deixe de molho a semente que quer experimentar por no m\u00ednimo 4h (o leite de coco n\u00e3o precisa deixar de molho, a menos que queira germin\u00e1-lo, o que \u00e9 uma \u00f3tima op\u00e7\u00e3o nutricional, mas germinar um coco seco precisa de paci\u00eancia, \u00e0s vezes leva um m\u00eas ou mais para ele despontar o \u201cnarizinho\u201d indicando que germinou);<br \/>\n2. Dispense essa \u00e1gua do molho;<br \/>\n3. Bata no liquidificador na propor\u00e7\u00e3o 1:3, ou seja, uma parte de semente (ou coco ralado) para 3 partes de \u00e1gua. (se quiser mais denso bata com menos \u00e1gua ou use, no m\u00e1ximo, 4 partes de \u00e1gua para 1 de semente, caso queira mais ralo.<br \/>\n4. Coe. O leite de coco, pode ser coado no coado tradicional mesmo, por\u00e9m os outros \u00e9 ideal coar com um paninho de voal fininho, a fim de que as fibras n\u00e3o deixem seu leite ran\u00e7oso.<br \/>\n5. Est\u00e1 pronto! Pode-se fazer bolos, tortas, biscoitos, iogurte, papa, ou simplesmente tomar com caf\u00e9 ou chocolate.<\/p>\n<p><strong>Mingau de aveia super pr\u00e1tico<\/strong><br \/>\n1. Depois de feito um leitinho vegetal bem consistente com 1\/2 xic. de qualquer oleaginosa j\u00e1 hidratada\u00a0 &#8211; castanhas, am\u00eandoas, nozes, amendoim&#8230; (Eu gosto muito de usar sementes de girassol sem casca), \u00a0batidas no liquidificador com 1 xic. de \u00e1gua\u00a0(n\u00e3o precisa ser coado)<br \/>\nJuntar com:<br \/>\n2. 2 col. Sopa de aveia em flocos<br \/>\n3. 1 col sopa de chia<br \/>\n4. Peda\u00e7os de t\u00e2maras secas e ou passas para dar um docinho. (Opcional)<br \/>\n5. Uma Pitadinha de nada de sal<br \/>\n6. Melado ou a\u00e7\u00facar de sua prefer\u00eancia (uso demerara misturado com canela propor\u00e7\u00e3o 1:1)<br \/>\nColoque tudo em um pote de vidro, e leve \u00e0 geladeira da noite para o dia, ou pelo menos por 3h, e pronto!<\/p>\n<p><strong>Yogurte de leite de coco<\/strong><br \/>\n1. Faz-se um leite de coco bem grossinho (de prefer\u00eancia com o coco germinado), da\u00ed usa uns 500ml e coloca uma c\u00e1psula de kefir ou qualquer outro lactobacillus que vende nas farm\u00e1cias em c\u00e1psulas (tipo floratil, repoflor&#8230;). O trabalho que d\u00e1 \u00e9 abrir uma c\u00e1psula e derramar o pozinho no leite.<br \/>\nDetalhe: faz o leite de coco com \u00e1gua morninha (quente demais n\u00e3o pois matar\u00e1 as bact\u00e9rias e n\u00e3o fermentar\u00e1), para acordar nossas amadas bact\u00e9rias. O ponto da temperatura da \u00e1gua \u00e9 voc\u00ea colocar seu dedo imerso na \u00e1gua e poder suportar a temperatura por 5 segundos.<br \/>\n2. Cobre o pote e espera por at\u00e9 10h fora da geladeira para fermentar.<br \/>\n3. Depois vai para a geladeira.<br \/>\n4. E em 2h t\u00e1 geladinho.<br \/>\n5. Pode ado\u00e7ar com melado ou o a\u00e7\u00facar que quiser. Ou bater com frutas ou geleia, para deixar docinho, pois fica bem azedinho.<\/p>\n<p><strong>Alm\u00f4ndegas de lentilha<\/strong><br \/>\n1. Das lentilhas cozidas e temperadas que geralmente sobram do almo\u00e7o, pode-se colocar chimichurri, alho frito (mas pode ser cebola e alho refogados tamb\u00e9m) e mais um salzinho, cuidado para n\u00e3o temperar demais! Siga provando ;)<br \/>\n2. Acrescente tamb\u00e9m gergelim hidratado (por no m\u00ednimo 2h) para agregar valor nutricional e a\u00ed, al\u00e9m de prote\u00ednas, temos um prato rico em c\u00e1lcio, magn\u00e9sio etc. (opcional)<br \/>\n3. Misturar na centr\u00edfuga para fazer uma massinha \u00famida, eu uso um Mixer (daqueles de m\u00e3o, super pr\u00e1tico)<br \/>\n4. Depois vai juntando e misturando com as m\u00e3os o polvilho doce, aos poucos.<br \/>\n5. Vai testando at\u00e9 dar o ponto de fazer as bolinhas. Elas ficam meio grudentas na m\u00e3o, mas d\u00e1 p fazer, uma boa \u00e9 ir lavando a m\u00e3o e fazendo as bolinhas com as m\u00e3os molhadas para eles n\u00e3o grudarem tanto.<br \/>\n6. Colocar as bolinhas no prato ou forma untados com \u00f3leo e vai ao forno ou na fritadeira sem \u00f3leo. Em 15 minutinhos fica pronto na fritadeira, no forno leva uns 30 minutos. Ver se t\u00e1 douradinho e pronto!<br \/>\nPode servir com v\u00e1rios molhos, uso muito o de tomate e ralo castanha do Par\u00e1 por cima.<\/p>\n<p><em>Bon app\u00e9tit!<\/em><\/p>\n<p>PS: Para qualquer d\u00favida, ou para mais receitinhas, voc\u00ea pode visitar meu instagram: @gabrielasencades<br \/>\nPode me mandar mensagem por l\u00e1 sobre d\u00favidas culin\u00e1rias, adoro responder essas quest\u00f5es. Sempre estou pesquisando algo sobre alimenta\u00e7\u00e3o e nutri\u00e7\u00e3o e o que eu n\u00e3o souber eu corro atr\u00e1s para responder de forma segura. ;)<\/p>\n<p align=\"JUSTIFY\"><b><img decoding=\"async\" loading=\"lazy\" class=\" wp-image-32742 alignleft\" src=\"http:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2018\/03\/Gabriela-Sencades-MIgge.jpg\" sizes=\"(max-width: 171px) 100vw, 171px\" srcset=\"http:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2018\/03\/Gabriela-Sencades-MIgge.jpg 208w, http:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2018\/03\/Gabriela-Sencades-MIgge-198x300.jpg 198w\" alt=\"\" width=\"171\" height=\"259\" \/><\/b><\/p>\n<p align=\"JUSTIFY\"><b>* Gabriela Sencades Migge<\/b>\u00a0\u00e9 terapeuta hol\u00edstica, co-fundadora do Espa\u00e7o Cuidar, mestra em reiki, frequenciadora de luz, aur\u00edculoterapeuta, terapeuta floral, terapeuta pr\u00e2nica, thetahealer, facilitadora em medita\u00e7\u00e3o. Realiza atendimentos presenciais no bairro das Gra\u00e7as, no Recife-PE, Brasil.<\/p>\n<p align=\"JUSTIFY\"><strong>Marque sua consulta pelo n\u00famero:<\/strong>\u00a0(81) 9.9163-5351 (claro\/whatsapp).<br \/>\n<strong>Facebook:<\/strong>\u00a0gabrielasencades<br \/>\n<strong>Atendimentos via Skype:<\/strong>\u00a0Gabi Sencades<\/p>\n","protected":false},"excerpt":{"rendered":"<p>|\u00a0Por Gabriela Sencades Migge*\u00a0| No artigo anterior &#8216;Amar a Deus Amando a Si Mesmo&#8216;, um \u00faltimo ponto foi uma sugest\u00e3o de pr\u00e1tica chamada de Metabhavana (medita\u00e7\u00e3o do amor universal), que consiste na repeti\u00e7\u00e3o e visualiza\u00e7\u00e3o do sentido das seguintes frases: 1. Que eu seja feliz (se visualize sendo e sentindo-se feliz e assim por diante); [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":34812,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[220,623],"tags":[50,499,377],"acf":[],"publishpress_future_action":{"enabled":false,"date":"1969-12-31 21:00:00","action":"","terms":[],"taxonomy":"","browser_timezone_offset":0},"_links":{"self":[{"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/posts\/34811"}],"collection":[{"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/comments?post=34811"}],"version-history":[{"count":0,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/posts\/34811\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/media\/34812"}],"wp:attachment":[{"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/media?parent=34811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/categories?post=34811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/tags?post=34811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}