

{"id":32741,"date":"2018-04-01T06:00:13","date_gmt":"2018-04-01T09:00:13","guid":{"rendered":"http:\/\/portalfloresnoar.com\/floresnoar\/?p=32741"},"modified":"2018-03-31T13:54:49","modified_gmt":"2018-03-31T16:54:49","slug":"integrando-saude-pequenas-crueldades-o-que-voce-anda-cultivando-para-sua-vida","status":"publish","type":"post","link":"https:\/\/portalfloresnoar.com\/floresnoar\/integrando-saude-pequenas-crueldades-o-que-voce-anda-cultivando-para-sua-vida\/","title":{"rendered":"[INTEGRANDO SA\u00daDE] Pequenas Crueldades &#8211; O que voc\u00ea anda cultivando para sua vida?"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-32743\" src=\"http:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2018\/03\/foto-pixabay-free.jpg\" alt=\"\" width=\"600\" height=\"359\" srcset=\"https:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2018\/03\/foto-pixabay-free.jpg 600w, https:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2018\/03\/foto-pixabay-free-300x180.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/p>\n<p>|\u00a0<em>Por Gabriela Sencades MIgge<\/em>* |<\/p>\n<p style=\"text-align: right;\"><em>\u201cExiste apenas uma resposta apropriada a ser dada por uma pessoa que testemunha o sofrimento de outra pessoa: como posso ajudar?\u201d<\/em><br \/>\n<em> (Alan Wallace. Budismo com Atitude p. 61)<\/em><\/p>\n<p>Ao longo dos meus 34 anos de vida tive a oportunidade de conhecer muita gente, de observar, entrar em suas vidas, alegrar-me, chorar e sempre aprender muito. Em todas as situa\u00e7\u00f5es, cada pessoa conhecida traz um mundo de experi\u00eancias e perspectivas. E, por isso, cada pessoa \u00e9 um grande professor a ser apreciado e descoberto.<\/p>\n<p>Apesar de cada mundo ser bem particular e n\u00e3o podermos nunca julgar os outros, afinal cada ser \u00e9 do jeito que \u00e9 e ponto final, no sentido de que n\u00e3o precisamos mudar ningu\u00e9m ou enquadr\u00e1-lo ao que nos agrada (afinal toler\u00e2ncia \u00e9 uma boa chave para um grande aprendizado). Podemos apenas observar, sem julgamentos, achismos ou opini\u00f5es e com isso aprendemos a aceitar, pois olhamos para os seres destitu\u00eddos dos v\u00e9us de nossa pr\u00f3pria ignor\u00e2ncia e o abra\u00e7amos com muita honestidade.<\/p>\n<p>Por\u00e9m, quando n\u00e3o percebemos o outro e toda sua \u201cbagagem\u201d (tudo aquilo que constitui o seu mundo), passamos a julg\u00e1-lo, n\u00e3o o compreendemos bem e por isso o desrespeitamos. Queremos, de forma intolerante, que o outro se adeque de qualquer modo ao nosso pr\u00f3prio jeito de enxergar o mundo. Nesse momento deixamos de ser humildes e curiosos alunos da nossa pr\u00f3pria \u201cmiss\u00e3o\u201d aqui nesse mundo e passamos a ser geradores de sofrimento, autorit\u00e1rios e controladores.<\/p>\n<p>N\u00e3o precisa ser nenhum Hittler para ser uma pessoa manipuladora e\/ou maquiav\u00e9lica, pelo contr\u00e1rio! Muitas vezes o controle se disfar\u00e7a com uma cara meiga, ing\u00eanua, amistosa, cheias de falsa mod\u00e9stia e companheirismo.<\/p>\n<p>Grandes manipuladores est\u00e3o mais pr\u00f3ximos do que se imagina, estabelecendo conex\u00f5es de acordo com seus pr\u00f3prios interesses. Tais pessoas apresentam uma cara amig\u00e1vel, mas s\u00e3o muito cr\u00edticos pelas costas, chantagistas emocionais, usam de v\u00e1rias performances para conseguir o que querem.<\/p>\n<p>Bem, se voc\u00ea detectou algu\u00e9m assim ao seu redor&#8230; REZE por essa pessoa. Certamente esse ser n\u00e3o \u00e9 feliz. \u00c9 uma pessoa vazia de si mesma e busca um sentido em sua vida se \u201capropriando\u201d da vida do outro. Reze sempre por essa pessoa. Pense que ela pode ser feliz, deseje isso para ela fortemente, mesmo que pare\u00e7a meio falso no come\u00e7o, v\u00e1 desejando a felicidade desse ser at\u00e9 soar verdadeiro para voc\u00ea.<\/p>\n<p>Por\u00e9m, se voc\u00ea detectou tais caracter\u00edsticas em voc\u00ea mesmo, parab\u00e9ns! Temos agora muito o que contemplar e liberar com honestidade e humildade verdadeiras.<\/p>\n<p>Se voc\u00ea j\u00e1 se percebeu rindo quando qualquer pessoa se d\u00e1 mal, seja com as m\u00ednimas coisas, como um trope\u00e7\u00e3o, por exemplo, poder\u00edamos j\u00e1 come\u00e7ar por a\u00ed. Por que sentimos isso? Por que nosso primeiro impulso \u00e9 rir ou criticar o outro ao inv\u00e9s de sentir verdadeiramente o que o outro est\u00e1 passando e partir para ajudar?<\/p>\n<p>Por que elogiar algo que n\u00e3o gostamos? E depois, pelas costas, come\u00e7armos a rir ou criticar o outro pelo motivo do qual o elogiamos?<br \/>\nPor que ter certas atitudes esperando que o outro \u201cse d\u00ea mal\u201d? Como, por exemplo, a pessoa que oferece carne a um vegetariano dizendo que aquilo n\u00e3o tem carne, que ele pode comer. Ou querer humilhar o outro na frente dos demais apontando seus \u201cdefeitos\u201d, \u201cfalhas\u201d, \u201cerros\u201d, \u201cignor\u00e2ncias\u201d.<\/p>\n<p>Por que oferecer algo que n\u00e3o est\u00e1 muito bom para o outro se nem voc\u00ea mesmo tem coragem de experimentar? Por que bater em algu\u00e9m que escolheu algo diferente de voc\u00ea? Por que rir de quem apanha? Ou achar que foi bem feito?<\/p>\n<p>Repare que se formos a fundo com as nossas \u201cpequenas crueldades\u201d podemos perceber um po\u00e7o de car\u00eancia e desolamento localizado em n\u00f3s mesmos. Quando agimos assim, nem percebemos, mas \u00e9 como se estiv\u00e9ssemos atordoados em nosso pr\u00f3prio caminho, sem saber para onde ir e nos \u201calegramos\u201d de ver o outro t\u00e3o mal ou pior do que n\u00f3s.<\/p>\n<p>Nos \u201cnivelamos por baixo\u201d. Como se fosse um pensamento mesquinho que reincidentemente toma conta de n\u00f3s \u201cJ\u00e1 que estou mal, fico feliz por voc\u00ea estar t\u00e3o mal ou pior do que eu\u201d.<\/p>\n<p>Com tais atitudes nutrimos mesquinhez, ego\u00edsmo e crueldade. Vivemos a pequenez de uma vida isolada, limitada, mesmo tendo um potencial infinito, mesmo podendo a qualquer momento ascender a vibra\u00e7\u00f5es sutis, mais plenas, autoconfiantes, generosas e compassivas. E justamente por falta dessa perspectiva acabamos fadados ao confinamento de nossos egos.<\/p>\n<p>O resultado disso \u00e9 ter um plexo solar super congestionado, voltado para o \u201ceu\u201d, \u201cmeu\u201d \u201ce os outros que se lixem\u201d. O card\u00edaco se fecha com grandes possibilidades de desenvolver depress\u00e3o, pois, quando o chacra card\u00edaco est\u00e1 fechado, n\u00e3o h\u00e1 espa\u00e7o para rela\u00e7\u00f5es sinceras em que se \u201cveja\u201d o outro com compassividade e amorosidade. Confesso que quando encontro algu\u00e9m com o card\u00edaco fechado o meu pr\u00f3prio card\u00edaco tende a se abrir mais e acolher tal ser nesse estado, pois esse ser est\u00e1 gravemente doente, incapaz de enxergar os outros, apenas v\u00ea suas pr\u00f3prias necessidades. \u201cCora\u00e7\u00e3o gelado!\u201d<\/p>\n<p>Pessoas assim s\u00e3o realmente muito s\u00f3s. Mesmo que tenham uma multid\u00e3o em torno delas, querendo apoiar e ajudar e que tamb\u00e9m precisam de seu apoio e de sua ajuda, elas ficam cegas demais para enxergar o que n\u00e3o considera bom para elas mesmas. Estas vivem em \u201cautopiedade\u201d reclamando e resmungando \u201coh mundo cruel\u201d, \u201co que fiz para merecer esse castigo\u201d. Dessa forma, cheios de amargura e \u201cauto-vitimiza\u00e7\u00e3o\u201d nossas vidas n\u00e3o ter\u00e3o sentido porque o outro n\u00e3o faz o que queremos.<\/p>\n<p>Nesse sentido, eu pergunto: at\u00e9 quando vamos querer \u201cpuxar as r\u00e9deas\u201d da vida dos outros se a nossa pr\u00f3pria vida est\u00e1 fora de controle? Que grande necessidade \u00e9 essa de ter coisas e seres sob nosso comando ou poder, se nem nossa pr\u00f3pria mente somos capazes de olhar com coragem, amorosidade e respeito para enfim podermos nos entendermos, perdoarmos e acolhermos?<\/p>\n<p>O caminho mais direto para soltarmos o controle \u00e9 contemplarmos a nossa mente. Por que tais coisas e seres nos incomodam tanto? Por que precisamos nos sentir melhores, maiores e mais bonitos que os outros?<\/p>\n<p>N\u00e3o \u00e9 um caminho muito f\u00e1cil, mas se contemplado com honestidade \u00e9 o mais r\u00e1pido e definitivo para transmutarmos toda a nossa negatividade, que sempre fizemos quest\u00e3o de n\u00e3o enxergar, pois estamos a vida toda colocando para \u201cbaixo do tapete\u201d aquelas \u201csujeirinhas\u201d que n\u00e3o queremos ver, mas que afinal fazem parte do que somos tamb\u00e9m!<\/p>\n<p>Tal sujeirinha mesmo debaixo do tapete ainda est\u00e1 l\u00e1! E enquanto n\u00e3o for \u201cauto-removida\u201d n\u00e3o h\u00e1 terapia que d\u00ea jeito, pois n\u00f3s terapeutas vamos limpar sua energia, colocar os chacras para se movimentar adequadamente, descongestionar, energizar, restaurar, transmutar cren\u00e7as&#8230; por\u00e9m, se n\u00e3o houver a vontade de vasculhar seu mundo interno at\u00e9 que n\u00e3o haja mais obst\u00e1culos, aquela \u201csujeirinha\u201d reincidir\u00e1 e suas condi\u00e7\u00f5es de doen\u00e7a e sofrimento retornar\u00e3o.<\/p>\n<p>O terapeuta ajuda e muito, mas nunca poder\u00e1 oferecer ao cliente a \u201ccura definitiva\u201d se esta n\u00e3o for o objetivo dele tamb\u00e9m. Se n\u00e3o se colabora, se n\u00e3o se investiga, se n\u00e3o se procura transmutar todo obscurecimento e as causas de adoecimento e sofrimento, tais causas reincidir\u00e3o, de novo e de novo. Seremos sempre marionetes de nossas emo\u00e7\u00f5es mais densas como orgulho, inveja, car\u00eancia, medo.<\/p>\n<p>Voc\u00eas j\u00e1 repararam como \u00e9 mesquinha e carente uma competi\u00e7\u00e3o? Queremos \u201cbrilhar\u201d em detrimento do \u201capagar\u201d dos outros. Mas, c\u00e1 entre n\u00f3s, o c\u00e9u \u00e9 mais belo quando est\u00e1 mais estrelado! Se considerarmos que somos p\u00f3 de estrelas, entendemos que nascemos para brilhar, todos n\u00f3s! O c\u00e9u \u00e9 infinito e sempre abrigar\u00e1 todas as estrelas. H\u00e1 plenitude quando brilhamos e auxiliamos a brilhar. Dessa forma pergunto: o que queremos cultivar em nossas vidas?<\/p>\n<p>E ent\u00e3o? Preparados para come\u00e7ar a transmutar?<\/p>\n<p style=\"text-align: right;\"><em>\u201cSe voc\u00ea achar que esses ensinamentos s\u00e3o bem fundamentados e ben\u00e9ficos, ent\u00e3o sim, por favor, coloquemos em pr\u00e1tica. Se n\u00e3o, continue buscando!\u201d<\/em><br \/>\n<em> (Alan Wallace. Budismo Com Atitude. P\u00e1g72)<\/em><\/p>\n<p><em><strong>Bibliografia Sugerida<\/strong><\/em><br \/>\n<em> Correia, Ana Karina de Sousa. Chakras, A Influ\u00eancia dos Chakras nos aspectos emocionais e fisiol\u00f3gicos do ser humano. Fortaleza: Funda\u00e7\u00e3o Edson Queiroz, 2007<\/em><br \/>\n<em> Samten, Padma. A Roda da Vida Como Caminho Para a Lucidez. S\u00e3o Paulo: Peir\u00f3polis, 2010<\/em><br \/>\n<em> Sui, Mestre Choa Kok, Ci\u00eancia da Cura Pr\u00e2nica: Manual Pr\u00e1tica Na Cura da Energia, S\u00e3o Paulo: Ebei Editora, 2015.<\/em><br \/>\n<em> Walace, Alan. Budismo com Atitude, Teres\u00f3polis: L\u00facida Letra, 2017.<\/em><\/p>\n<p align=\"JUSTIFY\"><b><img decoding=\"async\" loading=\"lazy\" class=\" wp-image-32742 alignleft\" src=\"http:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2018\/03\/Gabriela-Sencades-MIgge.jpg\" alt=\"\" width=\"171\" height=\"259\" srcset=\"https:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2018\/03\/Gabriela-Sencades-MIgge.jpg 208w, https:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2018\/03\/Gabriela-Sencades-MIgge-198x300.jpg 198w\" sizes=\"(max-width: 171px) 100vw, 171px\" \/><\/b><\/p>\n<p align=\"JUSTIFY\">\n<p align=\"JUSTIFY\"><b>* Gabriela Sencades Migge<\/b> \u00e9 terapeuta hol\u00edstica, co-fundadora do Espa\u00e7o Cuidar, mestra em reiki, frequenciadora de luz, aur\u00edculoterapeuta, terapeuta floral, terapeuta pr\u00e2nica, thetahealer, facilitadora em medita\u00e7\u00e3o. Realiza atendimentos presenciais no bairro das Gra\u00e7as, no Recife-PE, Brasil.<\/p>\n<p align=\"JUSTIFY\">\n<strong>Marque sua consulta pelo n\u00famero:<\/strong> (81) 9.9163-5351 (claro\/whatsapp).<br \/>\n<strong>Facebook:<\/strong> gabrielasencades<br \/>\n<strong>Atendimentos via Skype:<\/strong> Gabi Sencades<\/p>\n","protected":false},"excerpt":{"rendered":"<p>|\u00a0Por Gabriela Sencades MIgge* | \u201cExiste apenas uma resposta apropriada a ser dada por uma pessoa que testemunha o sofrimento de outra pessoa: como posso ajudar?\u201d (Alan Wallace. Budismo com Atitude p. 61) Ao longo dos meus 34 anos de vida tive a oportunidade de conhecer muita gente, de observar, entrar em suas vidas, alegrar-me, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":32743,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[220,623],"tags":[499,136,30,147],"acf":[],"publishpress_future_action":{"enabled":false,"date":"1969-12-31 21:00:00","action":"","terms":[],"taxonomy":"","browser_timezone_offset":0},"_links":{"self":[{"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/posts\/32741"}],"collection":[{"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/comments?post=32741"}],"version-history":[{"count":0,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/posts\/32741\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/media\/32743"}],"wp:attachment":[{"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/media?parent=32741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/categories?post=32741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/tags?post=32741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}