

{"id":31693,"date":"2017-10-06T15:04:30","date_gmt":"2017-10-06T18:04:30","guid":{"rendered":"http:\/\/portalfloresnoar.com\/floresnoar\/?p=31693"},"modified":"2017-12-18T15:09:50","modified_gmt":"2017-12-18T18:09:50","slug":"agenda-pe-sri-prem-baba-realiza-satsang-e-sessao-de-autografos-no-recife-dia-1712","status":"publish","type":"post","link":"https:\/\/portalfloresnoar.com\/floresnoar\/agenda-pe-sri-prem-baba-realiza-satsang-e-sessao-de-autografos-no-recife-dia-1712\/","title":{"rendered":"[AGENDA PE] Sri Prem Baba realiza Satsang e sess\u00e3o de aut\u00f3grafos no Recife dia 17\/12"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-31694\" src=\"http:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2017\/12\/sri-prem-baba-no-recife.jpg\" alt=\"\" width=\"650\" height=\"650\" srcset=\"https:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2017\/12\/sri-prem-baba-no-recife.jpg 650w, https:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2017\/12\/sri-prem-baba-no-recife-150x150.jpg 150w, https:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2017\/12\/sri-prem-baba-no-recife-300x300.jpg 300w, https:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2017\/12\/sri-prem-baba-no-recife-100x100.jpg 100w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/p>\n<p>O mestre espiritual Sri Prem Baba realiza no Recife, no dia 17 de dezembro de 2017, um Satsang e uma sess\u00e3o de aut\u00f3grafos do seu mais recente livro &#8216;Prop\u00f3sito &#8211;\u00a0 A Coragem de Ser Quem Somos &#8216;.<\/p>\n<p>Sri Prem Baba nasceu no estado de S\u00e3o Paulo. Estudou Psicologia e Yoga. Tornou-se disc\u00edpulo do mestre Sri Sachcha Baba Maharaji Ji, da linhagem indiana Sachcha. Seu trabalho une conhecimentos para fortalecer valores humanos, espirituais e sociais e, com alcance global. Atualmente, existem centros representativos de sua miss\u00e3o na \u00cdndia, Estados Unidos, Europa, Israel, Argentina e Brasil. Entre as publica\u00e7\u00f5es assinadas por Sri Prem Baba est\u00e3o os livros &#8220;Amar e Ser Livre &#8211; As Bases Para Uma Nova Sociedade&#8221;, &#8220;Transformando o Sofrimento em Alegria&#8221;, e o mais recente: &#8220;O Prop\u00f3sito &#8211; A Coragem de Ser Quem Somos&#8221;.<\/p>\n<p><strong>SATSANG<\/strong> &#8211; O Satsang tem entrada gratuita e acontece das 15h \u00e0s 17h, na Escola de Forma\u00e7\u00e3o e Aperfei\u00e7oamento de Educadores do Recife Professor Paulo Freire, no bairro da Madalena. Satsang \u00e9 um termo em s\u00e2nscrito que descreve uma experi\u00eancia semelhante a uma palestra, onde o Mestre Espiritual transmite os seus ensinamentos e eventualmente responde a perguntas. As inscri\u00e7\u00f5es devem ser feitas atrav\u00e9s <a href=\"https:\/\/www.eventbrite.com.br\/e\/encontro-com-sri-prem-baba-tickets-41044363797\" target=\"_blank\" rel=\"noopener\">DESTE LINK<\/a>!<\/p>\n<p>ORIENTA\u00c7\u00d5ES GERAIS PARA QUEM VAI PARTICIPAR DO SATSANG<br \/>\n&#8211; As inscri\u00e7\u00f5es ser\u00e3o realizadas somente atrav\u00e9s deste sistema online.<br \/>\n&#8211; Caso desista de comparecer, por amor, cancele sua participa\u00e7\u00e3o atrav\u00e9s desse sistema. Dessa maneira voc\u00ea permite que outra pessoa, da fila de espera, possa participar.<br \/>\n&#8211; O comprovante de inscri\u00e7\u00e3o a sua vaga est\u00e1 garantida at\u00e9 \u00e0s 14h45. O comprovante poder\u00e1 ser apresentado impresso ou no celular. Ap\u00f3s esse hor\u00e1rio ser\u00e1 liberada a entrada das pessoas que est\u00e3o na lista de espera.<br \/>\n&#8211; Abriremos o audit\u00f3rio \u00e0s 15h e respeitaremos a ordem de chegada, que ser\u00e1 organizada por fila. As pessoas com necessidades especiais ter\u00e3o prioridade no acesso.<br \/>\n&#8211; As crian\u00e7as s\u00e3o bem-vindas e durante o evento devem permanecer sob os cuidados dos pais ou respons\u00e1vel, lembrando que o campo do sil\u00eancio deve ser cultivado.<br \/>\n&#8211; Leve sua garrafinha com \u00e1gua para manter-se hidratado e d\u00ea prefer\u00eancia para ir de transporte p\u00fablico<br \/>\n&#8211; N\u00e3o \u00e9 permitido o consumo de alimentos no audit\u00f3rio.<br \/>\n&#8211; N\u00e3o \u00e9 permitido o uso de celular no audit\u00f3rio, nem fotografar o evento, pois h\u00e1 uma equipe dedicada a isso.<\/p>\n<p>IMPORTANTE<br \/>\n<em>Este evento ser\u00e1 filmado e ao entrar o visitante AUTORIZA, gratuitamente, a eventual capta\u00e7\u00e3o de sua imagem, assim como uso desta para divulga\u00e7\u00f5es, inclusive de natureza comercial, de projetos ligados a Sri Prem Baba. Caso n\u00e3o esteja de acordo, por favor, identifique-se na mesa de inscri\u00e7\u00f5es.<\/em><\/p>\n<p><strong>Satsang com Sri Prem Baba<\/strong><br \/>\n<strong>Data:<\/strong> 17 de dezembro de 2017<br \/>\n<strong>Hor\u00e1rio<\/strong>: 15h \u00e0s 17h<br \/>\n<strong>Local:<\/strong> Escola de Forma\u00e7\u00e3o e Aperfei\u00e7oamento de Educadores do Recife Professor Paulo Freire &#8211; Rua Real da Torre, 299 &#8211; Madalena, Recife &#8211; PE.<br \/>\n<strong>Mais informa\u00e7\u00f5es:<\/strong> recife@awakenlove.global<br \/>\n<strong>Investimento:<\/strong> Evento gratuito \u2013 solicitamos a entrega, no dia do evento, de 1kg de alimento n\u00e3o perec\u00edvel (preferencialmente leite), para ser doado ao abrigo Cristo Redentor em Jaboat\u00e3o dos Guararapes.<br \/>\n<strong>Inscri\u00e7\u00f5es:<a href=\"https:\/\/www.eventbrite.com.br\/e\/encontro-com-sri-prem-baba-tickets-41044363797\" target=\"_blank\" rel=\"noopener\">\u00a0<\/a><\/strong>https:\/\/www.eventbrite.com.br\/e\/encontro-com-sri-prem-baba-tickets-41044363797<\/p>\n<p>*********************************************************<\/p>\n<p><strong>SESS\u00c3O DE AUT\u00d3GRAFOS<\/strong> &#8211; A Sess\u00e3o de Aut\u00f3grafos acontece, das 18h \u00e0s 20h, na Livraria Saraiva do Shopping RioMar.<\/p>\n<p>REGRAS DE PARTICIPA\u00c7\u00c3O NA SESS\u00c3O DE AUT\u00d3GRAFOS:<br \/>\n&#8211; Poder\u00e3o participar da sess\u00e3o de aut\u00f3grafos as pessoas que possu\u00edrem o livro &#8216;Prop\u00f3sito&#8217;;<br \/>\n&#8211; A participa\u00e7\u00e3o no evento est\u00e1 limitada a 150 senhas;<br \/>\n&#8211; A distribui\u00e7\u00e3o de senhas ser\u00e1 feita a partir das 16h;<br \/>\n&#8211; O portador da senha tem direito de autografar apenas 02 (dois) livros;<br \/>\n&#8211; A senha \u00e9 pessoal e intransfer\u00edvel;<br \/>\n&#8211; A apresenta\u00e7\u00e3o da senha \u00e9 obrigat\u00f3ria. No caso de extravio da senha, esta n\u00e3o ser\u00e1 substitu\u00edda e o portador perder\u00e1 o direito de participar da sess\u00e3o de aut\u00f3grafos;<br \/>\n&#8211; Uma vez chamada \u00e0 senha imediatamente posterior ao seu n\u00famero, em raz\u00e3o da ordem num\u00e9rica de atendimento, o portador dever\u00e1 retornar ao final da fila para esperar o atendimento;<br \/>\n&#8211; N\u00e3o ser\u00e3o permitidos aut\u00f3grafos em marcadores de livros, peda\u00e7os de papel etc;<br \/>\n&#8211; N\u00e3o ser\u00e3o permitidas selfies, grava\u00e7\u00e3o de \u00e1udio ou videos na mesa dos aut\u00f3grafos. Teremos um fot\u00f3grafo profissional e as fotos ser\u00e3o disponibilizadas em at\u00e9 3 dias \u00fateis na p\u00e1gina do facebook da Sextante.<\/p>\n<p><strong>Sess\u00e3o de aut\u00f3grafos com Sri Prem Baba<\/strong><br \/>\n<strong>Data:<\/strong> 17 de dezembro de 2017<br \/>\n<strong>Hor\u00e1rio:<\/strong> 18h \u00e0s 20h<br \/>\n<strong>Local:<\/strong> Livraria Saraiva do Shopping RioMar<br \/>\n<strong>Mais informa\u00e7\u00f5es:<\/strong> recife@awakenlove.global<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O mestre espiritual Sri Prem Baba realiza no Recife, no dia 17 de dezembro de 2017, um Satsang e uma sess\u00e3o de aut\u00f3grafos do seu mais recente livro &#8216;Prop\u00f3sito &#8211;\u00a0 A Coragem de Ser Quem Somos &#8216;. Sri Prem Baba nasceu no estado de S\u00e3o Paulo. Estudou Psicologia e Yoga. Tornou-se disc\u00edpulo do mestre Sri [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":25694,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[8,214],"tags":[383,641],"acf":[],"publishpress_future_action":{"enabled":false,"date":"1969-12-31 21:00:00","action":"","terms":[],"taxonomy":"","browser_timezone_offset":0},"_links":{"self":[{"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/posts\/31693"}],"collection":[{"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/comments?post=31693"}],"version-history":[{"count":0,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/posts\/31693\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/media\/25694"}],"wp:attachment":[{"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/media?parent=31693"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/categories?post=31693"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/tags?post=31693"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}