

{"id":31076,"date":"2018-03-07T06:50:33","date_gmt":"2018-03-07T09:50:33","guid":{"rendered":"https:\/\/portalfloresnoar.com\/floresnoar\/?p=31076"},"modified":"2018-04-08T07:00:58","modified_gmt":"2018-04-08T10:00:58","slug":"agenda-pe-curso-de-formacao-em-psicoterapia-reencarnacionista-e-regressao-terapeutica-no-recife","status":"publish","type":"post","link":"https:\/\/portalfloresnoar.com\/floresnoar\/agenda-pe-curso-de-formacao-em-psicoterapia-reencarnacionista-e-regressao-terapeutica-no-recife\/","title":{"rendered":"[AGENDA PE] Curso de Forma\u00e7\u00e3o em Psicoterapia Reencarnacionista e Regress\u00e3o Terap\u00eautica no Recife"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-31077\" src=\"https:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2017\/10\/curso-psicoterapia-reencarnacionista-recife.jpg\" alt=\"\" width=\"598\" height=\"848\" srcset=\"https:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2017\/10\/curso-psicoterapia-reencarnacionista-recife.jpg 598w, https:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2017\/10\/curso-psicoterapia-reencarnacionista-recife-212x300.jpg 212w, https:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2017\/10\/curso-psicoterapia-reencarnacionista-recife-494x700.jpg 494w\" sizes=\"(max-width: 598px) 100vw, 598px\" \/><\/p>\n<p>A Associa\u00e7\u00e3o Brasileira de Psicoterapia Reencarnacionista (ABPR), em parceria com o Gerar Arteterapia e Bem-Estar, inicia no dia 7 de abril de 2018,\u00a0 no Recife, uma nova turma do Curso de Forma\u00e7\u00e3o em Psicoterapia Reencarnacionista e Regress\u00e3o Terap\u00eautica. As aulas ser\u00e3o ministradas pelos psicoterapeutas Reencarnacionistas Ciro Ferreira e Bernardo Freitas, uma vez por m\u00eas, sempre no primeiro s\u00e1bado do m\u00eas, das 8h30 \u00e0s 18h30. A mensalidade custa R$ 320,00. As inscri\u00e7\u00f5es j\u00e1 est\u00e3o abertas e podem ser realizadas atrav\u00e9s do telefone: (81) 3268.1749.<\/p>\n<p>\u201cA Psicoterapia Reencarnacionista come\u00e7ou a estruturar-se em 1996, em Porto Alegre, inicialmente comigo e gradativamente foram chegando mais terapeutas que entenderam a import\u00e2ncia da exist\u00eancia de uma psicoterapia baseada na Reencarna\u00e7\u00e3o aqui na Terra. Atualmente estamos com o Curso de Forma\u00e7\u00e3o em v\u00e1rios estados do Brasil\u201d, declara Mauro Kwitko, presidente da ABPR.<\/p>\n<p>O p\u00fablico-alvo s\u00e3o profissionais e estudantes da \u00e1rea da sa\u00fade (oficias ou alternativos) e\/ou m\u00e9diuns atuantes em Centros Esp\u00edritas e Espiritualistas. O pr\u00e9-requisito \u00e9 possuir o Ensino M\u00e9dio completo. O curso forma o participante para atuar com a Psicoterapia Reencarnacionista, profissionalmente em seu consult\u00f3rio ou gratuitamente em seu Centro Esp\u00edrita ou Espiritualista.<\/p>\n<p>A Psicoterapia Reencarnacionista \u00e9 uma nova escola psicol\u00f3gica que prop\u00f5e a fus\u00e3o da Psicoterapia com a Reencarna\u00e7\u00e3o. \u201c\u00c9 a Reencarna\u00e7\u00e3o no consult\u00f3rio psicoter\u00e1pico, e visa nos ajudar a encontrar a finalidade dessa atual encarna\u00e7\u00e3o, a nossa programa\u00e7\u00e3o pr\u00e9-reencarnat\u00f3ria e alcan\u00e7armos um real aproveitamento dessa atual passagem, no sentido da evolu\u00e7\u00e3o espiritual\u201d, com Kwitko.<\/p>\n<p><strong>FACILITADORES<\/strong><br \/>\nCIRO FERREIRA: psicoterapeuta reencarnacionista, formado no Rio de Janeiro (2012\/2013) por Mauro Kwitko (RS); experi\u00eancia como monitor em Bras\u00edlia, Teresina e Recife; ministrante de curso credenciado pela ABPR desde 2015; ministrou curso no Recife (2016\/2017) junto com Mauro Kwitko; palestrante nos Encontros Nacionais de Psicoterapia Reencarnacionista de Porto Alegre (2014), S\u00e3o Paulo (2015) e Rio de Janeiro (2017); gradua\u00e7\u00e3o em Psicologia e Engenharia Civil; p\u00f3s-graduando em Terapia Regressiva; mais de 25 anos de experi\u00eancia como professor; residente em Jo\u00e3o Pessoa.<\/p>\n<p>BERNARDO FREITAS: psicoterapeuta reencarnacionista, formado em Teresina (2014\/2015) por Roberto Tadeu e Denise Carillo (SP); experi\u00eancia como monitor em Teresina; ministrante de curso credenciado pela ABPR desde 2017; gradua\u00e7\u00e3o em Psicologia e p\u00f3s-gradua\u00e7\u00e3o em Psicologia Cl\u00ednica; palestrante com atua\u00e7\u00e3o em v\u00e1rios estados do Nordeste; mais de 15 anos de experi\u00eancia como professor; residente em Teresina.<\/p>\n<p><strong><em>Confira entrevista completa realizada pelo Portal Flores no Ar com Mauro Kwitko sobre a Psicoterapia Reencarnacionista <a href=\"https:\/\/portalfloresnoar.com\/floresnoar\/entrevista-com-mauro-kwitko-sobre-psicoterapia-reencarnacionista-e-regressao-terapeutica\/\" target=\"_blank\" rel=\"noopener\">aqui<\/a>!<\/em><\/strong><\/p>\n<p><em><strong>Mais informa\u00e7\u00f5es sobre a Psicoterapia Reencarnacionista podem ser acessadas em: <a href=\"http:\/\/www.portalabpr.org\/\" target=\"_blank\" rel=\"noopener\">http:\/\/www.portalabpr.org\/<\/a><\/strong><\/em><\/p>\n<p><strong>Curso de Forma\u00e7\u00e3o em Psicoterapia Reencarnacionista e Regress\u00e3o Terap\u00eautica<\/strong><br \/>\nIn\u00edcio: 07.04.2018 (s\u00e1bado)<br \/>\nDura\u00e7\u00e3o: 24 meses<br \/>\nDia das aulas: todo primeiro s\u00e1bado do m\u00eas<br \/>\nHora: 8h30 \u00e0s 18h30<br \/>\nLocal: GERAR ARTETERAPIA E BEM-ESTAR \u2013 Rua Jorge de Albuquerque, 103, Casa Forte, Recife-PE<br \/>\nInvestimento: R$ 320,00 (mensalidade)<\/p>\n<p><strong>Informa\u00e7\u00f5es\/Inscri\u00e7\u00f5es:<\/strong><br \/>\nTelefone: (81) 3268.1749 \/ (83) 99985.1241<br \/>\nE-mail: ciroferreira.psi@gmail.com<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Associa\u00e7\u00e3o Brasileira de Psicoterapia Reencarnacionista (ABPR), em parceria com o Gerar Arteterapia e Bem-Estar, inicia no dia 7 de abril de 2018,\u00a0 no Recife, uma nova turma do Curso de Forma\u00e7\u00e3o em Psicoterapia Reencarnacionista e Regress\u00e3o Terap\u00eautica. As aulas ser\u00e3o ministradas pelos psicoterapeutas Reencarnacionistas Ciro Ferreira e Bernardo Freitas, uma vez por m\u00eas, sempre [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":32210,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[8,214],"tags":[167,158],"acf":[],"publishpress_future_action":{"enabled":false,"date":"1969-12-31 21:00:00","action":"","terms":[],"taxonomy":"","browser_timezone_offset":0},"_links":{"self":[{"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/posts\/31076"}],"collection":[{"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/comments?post=31076"}],"version-history":[{"count":0,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/posts\/31076\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/media\/32210"}],"wp:attachment":[{"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/media?parent=31076"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/categories?post=31076"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/tags?post=31076"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}