

{"id":29819,"date":"2017-01-01T10:48:54","date_gmt":"2017-01-01T13:48:54","guid":{"rendered":"https:\/\/portalfloresnoar.com\/floresnoar\/?p=29819"},"modified":"2018-02-02T14:29:21","modified_gmt":"2018-02-02T17:29:21","slug":"agenda-pe-terapias-para-o-feminino-com-goretti-melo-no-lazuli-espaco-terapeutico","status":"publish","type":"post","link":"https:\/\/portalfloresnoar.com\/floresnoar\/agenda-pe-terapias-para-o-feminino-com-goretti-melo-no-lazuli-espaco-terapeutico\/","title":{"rendered":"[AGENDA PE] Terapias para o Feminino, com Goretti Melo, no Lazuli Espa\u00e7o Terap\u00eautico"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-29829\" src=\"https:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2017\/07\/terapia-para-mulheres-no-Recife_.jpg\" alt=\"\" width=\"720\" height=\"456\" srcset=\"https:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2017\/07\/terapia-para-mulheres-no-Recife_.jpg 720w, https:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2017\/07\/terapia-para-mulheres-no-Recife_-300x190.jpg 300w, https:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2017\/07\/terapia-para-mulheres-no-Recife_-700x443.jpg 700w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/p>\n<p>A terapeuta Goretti Melo realiza atendimentos individuais e em grupos com Florais e Ben\u00e7\u00e3o e Cura do \u00datero, auxiliando mulheres nos processos de cura e autoconhecimento. Os encontros acontecem no Lazuli Espa\u00e7o Terap\u00eautico, localizado no bairro da na Encruzilhada, no Recife.<\/p>\n<p>Goretti Melo\u00a0\u00e9 terapeuta floral e de Alinhamento Sexual Multidimensional, Moon Mother, professora de Reiki e Deeksha Giver e facilitadora do Retorno de Afrodite. Tem forma\u00e7\u00e3o na Doce Medicina e \u00e9 condutora de C\u00edrculos de Mulheres. Desde 2013 vem numa Jornada com o Sagrado Feminino realizando workshops e encontros voltados para a espiritualidade feminina.<\/p>\n<p><strong>Terapia Floral para o Feminino<\/strong><br \/>\nA terapia floral utiliza as ess\u00eancias florais, extratos l\u00edquidos de flores silvestres geralmente usados de forma oral. Seu uso proporciona uma atua\u00e7\u00e3o sutil e transformadora equilibrando e trazendo bem estar emocional, mental, f\u00edsico e espiritual.<\/p>\n<p>Nesse trabalho voltado especificamente para mulheres a terapia floral vai auxiliar no equil\u00edbrio emocional da mulher ajudando a lidar com as v\u00e1rias quest\u00f5es do universo feminino como Menopausa, climat\u00e9rio, TPM, Gravidez. Trabalha tamb\u00e9m com quest\u00f5es ligadas a sexualidade ajudando a trazer mais auto percep\u00e7\u00e3o emocional e corporal.<br \/>\n(Atendimento individual)<\/p>\n<p><strong>A Ben\u00e7\u00e3o do \u00datero<\/strong><br \/>\n\u00c9 um sistema de cura suave e poderoso que desperta as energias femininas de transforma\u00e7\u00e3o e cura.\u00a0Cura os padr\u00f5es profundos das nossas ancestrais e do nosso passado, liberta essas velhas energias que se mant\u00eam presas a n\u00f3s e traz empoderamento, amor, beleza e gra\u00e7a.<br \/>\n(Pode ser realizada Individual ou em pequenos grupos)<\/p>\n<p><strong>A Cura do \u00datero<\/strong><br \/>\nTrabalha os tr\u00eas principais centros da energia feminina. Auxilia o ciclo hormonal e abertura da consci\u00eancia espiritual. Ajuda a curar velhas feridas que possam ter sido guardadas no \u00fatero como: culpas, m\u00e1goas, abandono, viol\u00eancias, abusos, traumas no parto, cistos, miomas. Traz equil\u00edbrio\u00a0para o ciclo menstrual e tamb\u00e9m conduz a totalidade para quem n\u00e3o possui mais ciclo (menopausa).<br \/>\n(Pode ser realizada Individual ou em pequenos grupos)<\/p>\n<p>AGENDAMENTO DE CONSULTAS ATRAV\u00c9S DOS CONTATOS:<br \/>\n<strong>Telefone:<\/strong> (81) 98855- 6581 (TIM\/WhatsApp)<br \/>\n<strong>E-mail:<\/strong> falagorettimelo@gmail.com<\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-29822\" src=\"https:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2017\/07\/goretti-melo-terapias-para-o-feminino.jpg\" alt=\"\" width=\"650\" height=\"281\" srcset=\"https:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2017\/07\/goretti-melo-terapias-para-o-feminino.jpg 650w, https:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2017\/07\/goretti-melo-terapias-para-o-feminino-300x130.jpg 300w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; A terapeuta Goretti Melo realiza atendimentos individuais e em grupos com Florais e Ben\u00e7\u00e3o e Cura do \u00datero, auxiliando mulheres nos processos de cura e autoconhecimento. Os encontros acontecem no Lazuli Espa\u00e7o Terap\u00eautico, localizado no bairro da na Encruzilhada, no Recife. Goretti Melo\u00a0\u00e9 terapeuta floral e de Alinhamento Sexual Multidimensional, Moon Mother, professora de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":29828,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[8,224,214],"tags":[325,367,358,22,238],"acf":[],"publishpress_future_action":{"enabled":false,"date":"1969-12-31 21:00:00","action":"","terms":[],"taxonomy":"","browser_timezone_offset":0},"_links":{"self":[{"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/posts\/29819"}],"collection":[{"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/comments?post=29819"}],"version-history":[{"count":0,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/posts\/29819\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/media\/29828"}],"wp:attachment":[{"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/media?parent=29819"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/categories?post=29819"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/tags?post=29819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}