

{"id":28836,"date":"2017-02-17T16:03:27","date_gmt":"2017-02-17T19:03:27","guid":{"rendered":"http:\/\/portalfloresnoar.com\/floresnoar\/?p=28836"},"modified":"2017-05-01T12:06:10","modified_gmt":"2017-05-01T15:06:10","slug":"agenda-pe-curso-de-frequencias-de-luz-dias-29-e-30-de-abril-com-juan-saucedo-no-recife","status":"publish","type":"post","link":"https:\/\/portalfloresnoar.com\/floresnoar\/agenda-pe-curso-de-frequencias-de-luz-dias-29-e-30-de-abril-com-juan-saucedo-no-recife\/","title":{"rendered":"[AGENDA PE] Curso de Frequ\u00eancias de Luz dias 29 e 30 de abril, com Juan Saucedo, no Recife"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-28838\" alt=\"FrequenciaLuzJUAN-CURSO3\" src=\"http:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2017\/04\/FrequenciaLuzJUAN-CURSO3.jpg\" width=\"720\" height=\"1018\" srcset=\"https:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2017\/04\/FrequenciaLuzJUAN-CURSO3.jpg 720w, https:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2017\/04\/FrequenciaLuzJUAN-CURSO3-212x300.jpg 212w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/p>\n<p>O terapeuta\u00a0Juan Eduardo Saucedo Isaza facilita \u00a0nos dias 29 e 30 de abril de 2017, no Recife, das 10h \u00e0s 19h, o\u00a0Curso de Frequ\u00eancias de Luz, Terapia Qu\u00e2ntica Pleiadiana (N\u00edvel 1).<\/p>\n<p>\u201cA t\u00e9cnica de Frequ\u00eancias de Luz canaliza as energias sutis dos Emiss\u00e1rios de Luz pleiadianos, das entidades xam\u00e1nicas Cherokees e da Grande Fraternidade Branca.\u00a0Ajuda no processo de ascens\u00e3o espiritual, harmoniza\u00e7\u00e3o dos chacras e dos corpos energ\u00e9ticos, equilibrando a sa\u00fade f\u00edsica, emocional e mental, religando o indiv\u00edduo com seu Eu Superior\u201d, explica Juan.<\/p>\n<p>A t\u00e9cnica de Frequ\u00eancias de Luz\u00a0utiliza radiestesia, estudo dos chacras, imposi\u00e7\u00e3o de m\u00e3os, mantras e visualiza\u00e7\u00e3o de cores. O terapeuta ser\u00e1 iniciado com tambor e cristais de quartzo.<\/p>\n<p>CONTE\u00daDO PROGRAM\u00c1TICO DO CURSO<br \/>\n<strong>S\u00e1bado (29\/4)<\/strong><br \/>\nTransi\u00e7\u00e3o Planet\u00e1ria<br \/>\nMultidimensionalidade, O ser humano Hol\u00edstico e C\u00f3smico<br \/>\nOs corpos energ\u00e9ticos, Campo de energia Humana, Corpo Sutil ou Aura<br \/>\nO sistema de chacras<\/p>\n<p><strong>Domingo (30\/4)<\/strong><br \/>\nM\u00e9todo da Sess\u00e3o de Freq\u00fc\u00eancias de Luz<br \/>\nPr\u00e1tica do passo a passo<\/p>\n<p><strong>Local:<\/strong>\u00a0Galeria Maumau. Rua Nicar\u00e1gua 173, Espinheiro, Recife\/PE<\/p>\n<p><strong>Investimento:<\/strong>\u00a0R$ 400,00. 2x de R$ 200,00.<br \/>\n<em>Desconto:<\/em>\u00a0R$ 370,00 antes de 20 de abril. No cart\u00e3o ser\u00e1 cobrado uma taxa de 10%;<br \/>\n(Este valor inclui a apostila e p\u00eandulo e <em>Coffee Break<\/em>).<\/p>\n<p><em><strong>Obs.1:<\/strong> <\/em>\u00a0Um Cristal de Quartzo dever\u00e1 ser adquirido para a inicia\u00e7\u00e3o que ser\u00e1 no domingo e ser\u00e1 usado em cada sess\u00e3o que o terapeuta fizer. O Cristal serve como amplificador dos pensamentos e facilita o contato entre as dimens\u00f5es.<\/p>\n<p><em><strong>Obs.2:<\/strong> <\/em>O terapeuta precisar\u00e1 fazer 21 sess\u00f5es de gra\u00e7a como forma de treino para poder come\u00e7ar a cobrar e trabalhar mais com a t\u00e9cnica.<\/p>\n<p>MAIS INFORMA\u00c7\u00d5ES<br \/>\n<a href=\"mailto:juansisaza@gmail.com\" target=\"_blank\">juansisaza@gmail.com<\/a><br \/>\n(83) 9 9689 0355 (Whatsapp)<\/p>\n<p><a href=\"http:\/\/l.facebook.com\/l.php?u=http%3A%2F%2Fwww.frequenciasdeluz.com%2F&amp;h=4AQF0sZ_x&amp;enc=AZM16dRfJmVyIPMRJxR10AQrRZ-HO8M3YnN8O7C-xQBulBNeGDPOYplA3fiSkaYa9Tg&amp;s=1\" target=\"_blank\" rel=\"nofollow nofollow\" data-saferedirecturl=\"https:\/\/www.google.com\/url?hl=pt-BR&amp;q=http:\/\/l.facebook.com\/l.php?u%3Dhttp%253A%252F%252Fwww.frequenciasdeluz.com%252F%26h%3D4AQF0sZ_x%26enc%3DAZM16dRfJmVyIPMRJxR10AQrRZ-HO8M3YnN8O7C-xQBulBNeGDPOYplA3fiSkaYa9Tg%26s%3D1&amp;source=gmail&amp;ust=1477510808860000&amp;usg=AFQjCNFaBKHTE4FCvWgnswZp-pL7n7APtA\">www.frequenciasdeluz.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O terapeuta\u00a0Juan Eduardo Saucedo Isaza facilita \u00a0nos dias 29 e 30 de abril de 2017, no Recife, das 10h \u00e0s 19h, o\u00a0Curso de Frequ\u00eancias de Luz, Terapia Qu\u00e2ntica Pleiadiana (N\u00edvel 1). \u201cA t\u00e9cnica de Frequ\u00eancias de Luz canaliza as energias sutis dos Emiss\u00e1rios de Luz pleiadianos, das entidades xam\u00e1nicas Cherokees e da Grande Fraternidade Branca.\u00a0Ajuda [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":28837,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[8,214],"tags":[167,385],"acf":[],"publishpress_future_action":{"enabled":false,"date":"1969-12-31 21:00:00","action":"","terms":[],"taxonomy":"","browser_timezone_offset":0},"_links":{"self":[{"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/posts\/28836"}],"collection":[{"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/comments?post=28836"}],"version-history":[{"count":0,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/posts\/28836\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/media\/28837"}],"wp:attachment":[{"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/media?parent=28836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/categories?post=28836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/tags?post=28836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}