

{"id":28411,"date":"2017-02-14T11:26:42","date_gmt":"2017-02-14T14:26:42","guid":{"rendered":"http:\/\/portalfloresnoar.com\/floresnoar\/?p=28411"},"modified":"2017-03-21T10:48:45","modified_gmt":"2017-03-21T13:48:45","slug":"agenda-pe-domingo-tem-setubal-literario-com-palestras-intervencoes-artisticas-e-troca-de-livros","status":"publish","type":"post","link":"https:\/\/portalfloresnoar.com\/floresnoar\/agenda-pe-domingo-tem-setubal-literario-com-palestras-intervencoes-artisticas-e-troca-de-livros\/","title":{"rendered":"[AGENDA PE] Domingo tem Set\u00fabal Liter\u00e1rio, com palestras, interven\u00e7\u00f5es art\u00edsticas e troca de livros"},"content":{"rendered":"<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-28414\" alt=\"Programacao Setubal Literario\" src=\"http:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2017\/03\/Programacao-Setubal-Literario.jpeg\" width=\"650\" height=\"809\" srcset=\"https:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2017\/03\/Programacao-Setubal-Literario.jpeg 650w, https:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2017\/03\/Programacao-Setubal-Literario-241x300.jpeg 241w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/p>\n<p>O Coletivo Set\u00fabal realiza neste domingo, 19 de mar\u00e7o, o III Set\u00fabal Liter\u00e1rio,\u00a0das 12h \u00e0s 18h, na esquina das ruas Baltazar Passos com Cosmorama, em Set\u00fabal, no Recife. Haver\u00e1 palestras, interven\u00e7\u00f5es art\u00edsticas e troca de livros, al\u00e9m de pra\u00e7a de alimenta\u00e7\u00e3o. Uma \u00f3tima programa\u00e7\u00e3o para crian\u00e7as e adultos!<\/p>\n<p>&#8220;Como sociedade organizada, entendemos que a educa\u00e7\u00e3o \u00e9 a base para diversas mudan\u00e7as de comportamento necess\u00e1rias \u00e0 melhor conviv\u00eancia, e sabemos que a leitura \u00e9 parte importante deste processo, \u00e0 medida que estimula o pensamento cr\u00edtico, livre e a criatividade. Considerando tamb\u00e9m valores como sustentabilidade e senso de comunidade, estimulamos sempre que poss\u00edvel a troca como forma de intera\u00e7\u00e3o entre os vizinhos e mudan\u00e7a de cultura quanto ao consumo excessivo&#8221;, declaram os organizadores do Set\u00fabal Liter\u00e1rio.<\/p>\n<p>Quem for de carro, poder\u00e1 estacionar dentro do estacionamento do Col\u00e9gio Madre de Deus, um dos apoiadores do evento, junto \u00e0 Livraria MEC, Auto Escola Piloto, Cepe e RM Im\u00f3veis.<\/p>\n<p>PROGRAMA\u00c7\u00c3O<br \/>\n<strong>15h<\/strong> &#8211; <strong>Bate-papo com Nadezsha Bezerra<\/strong>, empreendedora e moradora do bairro, que usa o texto afetivo para criar presentes super originais. Ela ir\u00e1 explicar como as palavras podem ser melhor utilizadas e estimular os presentes a criarem seus pr\u00f3prios textos afetivos.<\/p>\n<p><strong>15h30 &#8211;<\/strong> <strong>Performance d&#8217;As Cumade<\/strong>, dupla po\u00e9tica composta pelas artistas Ana\u00edra Mahin e Lu Rabelo (moradora de Set\u00fabal). Na ocasi\u00e3o As Cumade tamb\u00e9m estar\u00e3o comercializando e autografando o Box de Cord\u00e9is d&#8217;As Cumade, contendo 4 folhetos de autoria das art<\/p>\n<p><strong>16h<\/strong> &#8211; <strong>Conta\u00e7\u00e3o de Hist\u00f3ria com O Tapete Voador<\/strong><\/p>\n<p><strong>17h<\/strong> &#8211; <strong>Lan\u00e7amento do livro Dona Boca<\/strong>, <strong>de Josu\u00e9 Limeira<\/strong><\/p>\n<p><em>Veja como chegar no mapa abaixo!<\/em><\/p>\n<p><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-full wp-image-28416\" alt=\"mapa setubal literario\" src=\"http:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2017\/03\/mapa-setubal-literario.jpg\" width=\"688\" height=\"446\" srcset=\"https:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2017\/03\/mapa-setubal-literario.jpg 688w, https:\/\/portalfloresnoar.com\/floresnoar\/wp-content\/uploads\/2017\/03\/mapa-setubal-literario-300x194.jpg 300w\" sizes=\"(max-width: 688px) 100vw, 688px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Coletivo Set\u00fabal realiza neste domingo, 19 de mar\u00e7o, o III Set\u00fabal Liter\u00e1rio,\u00a0das 12h \u00e0s 18h, na esquina das ruas Baltazar Passos com Cosmorama, em Set\u00fabal, no Recife. Haver\u00e1 palestras, interven\u00e7\u00f5es art\u00edsticas e troca de livros, al\u00e9m de pra\u00e7a de alimenta\u00e7\u00e3o. Uma \u00f3tima programa\u00e7\u00e3o para crian\u00e7as e adultos! &#8220;Como sociedade organizada, entendemos que a educa\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":28415,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[8,214],"tags":[295,456,69],"acf":[],"publishpress_future_action":{"enabled":false,"date":"1969-12-31 21:00:00","action":"","terms":[],"taxonomy":"","browser_timezone_offset":0},"_links":{"self":[{"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/posts\/28411"}],"collection":[{"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/comments?post=28411"}],"version-history":[{"count":0,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/posts\/28411\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/media\/28415"}],"wp:attachment":[{"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/media?parent=28411"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/categories?post=28411"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalfloresnoar.com\/floresnoar\/wp-json\/wp\/v2\/tags?post=28411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}